{"id":6129,"date":"2013-09-19T17:55:12","date_gmt":"2013-09-19T12:25:12","guid":{"rendered":"https:\/\/www.legalindia.in\/directory\/?p=6129"},"modified":"2014-11-12T16:25:23","modified_gmt":"2014-11-12T10:55:23","slug":"income-tax-office-nashik-maharashtra","status":"publish","type":"post","link":"https:\/\/www.legalindia.com\/directory\/income-tax-office-nashik-maharashtra","title":{"rendered":"Income Tax Office in Nashik Maharashtra"},"content":{"rendered":"<h2>Income Tax Office in Nashik Maharashtra<\/h2>\n<p>&nbsp;<\/p>\n<p><strong>Address:<\/strong><\/p>\n<p>Kendriya Rajaswa Bha Gadhari Chowk<\/p>\n<p>Old Agra Road<\/p>\n<p>Nashik &#8211; 422 002<\/p>\n<p>Maharashtra<\/p>\n<p>India<\/p>\n<p><strong>STD Code:<\/strong> 253<\/p>\n<p><strong>Phone no.:<\/strong> 0253-2575613<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Income Tax Office in Nashik Maharashtra &nbsp; Address: Kendriya Rajaswa Bha Gadhari Chowk Old Agra Road Nashik &#8211; 422 002 Maharashtra India STD Code: 253 Phone no.: 0253-2575613<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[12842],"tags":[13009,13008,12830,12829,12831,13005,13004,12828,13006,13007,12055,45285,13010],"class_list":["post-6129","post","type-post","status-publish","format-standard","hentry","category-income-tax-office","tag-address-of-income-tax-office-in-nashik-maharashtra","tag-contact-details-of-income-tax-office-in-nashik-maharashtra","tag-income-tax-office-in-bombay","tag-income-tax-office-in-maharashtra","tag-income-tax-office-in-mumbai","tag-income-tax-office-in-nashik","tag-income-tax-office-in-nashik-maharashtra","tag-income-tax-office-maharashtra","tag-income-tax-office-nashik","tag-income-tax-office-nashik-maharashtra","tag-income-tax-offices","tag-maharashtra","tag-phone-no-of-income-tax-office-in-nashik-maharashtra"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Income Tax Office in Nashik Maharashtra<\/title>\n<meta name=\"description\" content=\"Income Tax Office in Nashik Maharashtra\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.legalindia.com\/directory\/income-tax-office-nashik-maharashtra\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Income Tax Office in Nashik Maharashtra\" \/>\n<meta property=\"og:description\" content=\"Income Tax Office in Nashik Maharashtra\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.legalindia.com\/directory\/income-tax-office-nashik-maharashtra\" \/>\n<meta property=\"og:site_name\" content=\"Find a Lawyer in India - Legal Directory | Legal India\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LegalindiaCom\/\" \/>\n<meta property=\"article:published_time\" content=\"2013-09-19T12:25:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-11-12T10:55:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/www.legalindia.com\/directory\/wp-content\/uploads\/sites\/6\/2025\/09\/legal-india-icon.jpg?fit=512%2C512&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.legalindia.com\\\/directory\\\/income-tax-office-nashik-maharashtra#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.legalindia.com\\\/directory\\\/income-tax-office-nashik-maharashtra\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Income Tax Office in Nashik Maharashtra\",\"datePublished\":\"2013-09-19T12:25:12+00:00\",\"dateModified\":\"2014-11-12T10:55:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.legalindia.com\\\/directory\\\/income-tax-office-nashik-maharashtra\"},\"wordCount\":31,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.legalindia.com\\\/directory\\\/#organization\"},\"keywords\":[\"address of Income Tax Office in Nashik Maharashtra\",\"contact details of Income Tax Office in Nashik Maharashtra\",\"Income Tax Office in Bombay\",\"Income Tax Office in Maharashtra\",\"Income Tax Office in Mumbai\",\"Income Tax Office in Nashik\",\"Income Tax Office in Nashik Maharashtra\",\"Income Tax Office Maharashtra\",\"Income Tax Office Nashik\",\"Income Tax Office Nashik Maharashtra\",\"Income Tax Offices\",\"Maharashtra\",\"phone no. of Income Tax Office in Nashik Maharashtra\"],\"articleSection\":[\"Income Tax Office\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.legalindia.com\\\/directory\\\/income-tax-office-nashik-maharashtra#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.legalindia.com\\\/directory\\\/income-tax-office-nashik-maharashtra\",\"url\":\"https:\\\/\\\/www.legalindia.com\\\/directory\\\/income-tax-office-nashik-maharashtra\",\"name\":\"Income Tax Office in Nashik Maharashtra\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.legalindia.com\\\/directory\\\/#website\"},\"datePublished\":\"2013-09-19T12:25:12+00:00\",\"dateModified\":\"2014-11-12T10:55:23+00:00\",\"description\":\"Income Tax Office in Nashik Maharashtra\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.legalindia.com\\\/directory\\\/income-tax-office-nashik-maharashtra#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.legalindia.com\\\/directory\\\/income-tax-office-nashik-maharashtra\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.legalindia.com\\\/directory\\\/income-tax-office-nashik-maharashtra#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.legalindia.com\\\/directory\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Income Tax Office in Nashik Maharashtra\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.legalindia.com\\\/directory\\\/#website\",\"url\":\"https:\\\/\\\/www.legalindia.com\\\/directory\\\/\",\"name\":\"Find a Lawyer in India - Legal Directory | Legal India\",\"description\":\"Find and connect with advocates, lawyers, and law firms across India. Our free legal directory helps you search by location, practice area, and court for free.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.legalindia.com\\\/directory\\\/#organization\"},\"alternateName\":\"Free Directory of Lawyers and Law Firms in India | Legal India\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.legalindia.com\\\/directory\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.legalindia.com\\\/directory\\\/#organization\",\"name\":\"Legal Directory - Free Law Directory of India : Legal India\",\"alternateName\":\"Free Directory of Lawyers and Law Firms in India | Legal India\",\"url\":\"https:\\\/\\\/www.legalindia.com\\\/directory\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.legalindia.com\\\/directory\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.legalindia.com\\\/directory\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2025\\\/09\\\/legal-india-icon.jpg?fit=512%2C512&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.legalindia.com\\\/directory\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2025\\\/09\\\/legal-india-icon.jpg?fit=512%2C512&ssl=1\",\"width\":512,\"height\":512,\"caption\":\"Legal Directory - Free Law Directory of India : Legal India\"},\"image\":{\"@id\":\"https:\\\/\\\/www.legalindia.com\\\/directory\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LegalindiaCom\\\/\",\"https:\\\/\\\/x.com\\\/legal_india\"]},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\\\/\\\/www.legalindia.com\\\/directory\\\/author\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Income Tax Office in Nashik Maharashtra","description":"Income Tax Office in Nashik Maharashtra","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.legalindia.com\/directory\/income-tax-office-nashik-maharashtra","og_locale":"en_US","og_type":"article","og_title":"Income Tax Office in Nashik Maharashtra","og_description":"Income Tax Office in Nashik Maharashtra","og_url":"https:\/\/www.legalindia.com\/directory\/income-tax-office-nashik-maharashtra","og_site_name":"Find a Lawyer in India - Legal Directory | Legal India","article_publisher":"https:\/\/www.facebook.com\/LegalindiaCom\/","article_published_time":"2013-09-19T12:25:12+00:00","article_modified_time":"2014-11-12T10:55:23+00:00","og_image":[{"width":512,"height":512,"url":"https:\/\/i0.wp.com\/www.legalindia.com\/directory\/wp-content\/uploads\/sites\/6\/2025\/09\/legal-india-icon.jpg?fit=512%2C512&ssl=1","type":"image\/jpeg"}],"twitter_misc":{"Written by":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.legalindia.com\/directory\/income-tax-office-nashik-maharashtra#article","isPartOf":{"@id":"https:\/\/www.legalindia.com\/directory\/income-tax-office-nashik-maharashtra"},"author":{"name":"","@id":""},"headline":"Income Tax Office in Nashik Maharashtra","datePublished":"2013-09-19T12:25:12+00:00","dateModified":"2014-11-12T10:55:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.legalindia.com\/directory\/income-tax-office-nashik-maharashtra"},"wordCount":31,"commentCount":0,"publisher":{"@id":"https:\/\/www.legalindia.com\/directory\/#organization"},"keywords":["address of Income Tax Office in Nashik Maharashtra","contact details of Income Tax Office in Nashik Maharashtra","Income Tax Office in Bombay","Income Tax Office in Maharashtra","Income Tax Office in Mumbai","Income Tax Office in Nashik","Income Tax Office in Nashik Maharashtra","Income Tax Office Maharashtra","Income Tax Office Nashik","Income Tax Office Nashik Maharashtra","Income Tax Offices","Maharashtra","phone no. of Income Tax Office in Nashik Maharashtra"],"articleSection":["Income Tax Office"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.legalindia.com\/directory\/income-tax-office-nashik-maharashtra#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.legalindia.com\/directory\/income-tax-office-nashik-maharashtra","url":"https:\/\/www.legalindia.com\/directory\/income-tax-office-nashik-maharashtra","name":"Income Tax Office in Nashik Maharashtra","isPartOf":{"@id":"https:\/\/www.legalindia.com\/directory\/#website"},"datePublished":"2013-09-19T12:25:12+00:00","dateModified":"2014-11-12T10:55:23+00:00","description":"Income Tax Office in Nashik Maharashtra","breadcrumb":{"@id":"https:\/\/www.legalindia.com\/directory\/income-tax-office-nashik-maharashtra#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.legalindia.com\/directory\/income-tax-office-nashik-maharashtra"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.legalindia.com\/directory\/income-tax-office-nashik-maharashtra#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.legalindia.com\/directory\/"},{"@type":"ListItem","position":2,"name":"Income Tax Office in Nashik Maharashtra"}]},{"@type":"WebSite","@id":"https:\/\/www.legalindia.com\/directory\/#website","url":"https:\/\/www.legalindia.com\/directory\/","name":"Find a Lawyer in India - Legal Directory | Legal India","description":"Find and connect with advocates, lawyers, and law firms across India. Our free legal directory helps you search by location, practice area, and court for free.","publisher":{"@id":"https:\/\/www.legalindia.com\/directory\/#organization"},"alternateName":"Free Directory of Lawyers and Law Firms in India | Legal India","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.legalindia.com\/directory\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.legalindia.com\/directory\/#organization","name":"Legal Directory - Free Law Directory of India : Legal India","alternateName":"Free Directory of Lawyers and Law Firms in India | Legal India","url":"https:\/\/www.legalindia.com\/directory\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.legalindia.com\/directory\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/www.legalindia.com\/directory\/wp-content\/uploads\/sites\/6\/2025\/09\/legal-india-icon.jpg?fit=512%2C512&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.legalindia.com\/directory\/wp-content\/uploads\/sites\/6\/2025\/09\/legal-india-icon.jpg?fit=512%2C512&ssl=1","width":512,"height":512,"caption":"Legal Directory - Free Law Directory of India : Legal India"},"image":{"@id":"https:\/\/www.legalindia.com\/directory\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LegalindiaCom\/","https:\/\/x.com\/legal_india"]},{"@type":"Person","@id":"","url":"https:\/\/www.legalindia.com\/directory\/author"}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p6Hito-1AR","jetpack_likes_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/www.legalindia.com\/directory\/wp-json\/wp\/v2\/posts\/6129","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.legalindia.com\/directory\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.legalindia.com\/directory\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.legalindia.com\/directory\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.legalindia.com\/directory\/wp-json\/wp\/v2\/comments?post=6129"}],"version-history":[{"count":0,"href":"https:\/\/www.legalindia.com\/directory\/wp-json\/wp\/v2\/posts\/6129\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.legalindia.com\/directory\/wp-json\/wp\/v2\/media?parent=6129"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.legalindia.com\/directory\/wp-json\/wp\/v2\/categories?post=6129"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.legalindia.com\/directory\/wp-json\/wp\/v2\/tags?post=6129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}